{"id":4656,"date":"2024-09-10T11:02:37","date_gmt":"2024-09-10T09:02:37","guid":{"rendered":"https:\/\/gaf.kleve.de\/hp\/?post_type=event&#038;p=4656"},"modified":"2024-09-10T11:02:37","modified_gmt":"2024-09-10T09:02:37","slug":"klassenfahrt-jahrgang-10-4","status":"publish","type":"event","link":"https:\/\/gaf.kleve.de\/hp\/event\/klassenfahrt-jahrgang-10-4\/","title":{"rendered":"Klassenfahrt Jahrgang 10"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","categories":[54],"tags":[],"class_list":["post-4656","event","type-event","status-publish","hentry","category-termine"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Klassenfahrt Jahrgang 10 - Gesamtschule am Forstgarten Kleve<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gaf.kleve.de\/hp\/event\/klassenfahrt-jahrgang-10-4\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Klassenfahrt Jahrgang 10 - Gesamtschule am Forstgarten Kleve\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gaf.kleve.de\/hp\/event\/klassenfahrt-jahrgang-10-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Gesamtschule am Forstgarten Kleve\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gaf.kleve.de\\\/hp\\\/event\\\/klassenfahrt-jahrgang-10-4\\\/\",\"url\":\"https:\\\/\\\/gaf.kleve.de\\\/hp\\\/event\\\/klassenfahrt-jahrgang-10-4\\\/\",\"name\":\"Klassenfahrt Jahrgang 10 - Gesamtschule am Forstgarten Kleve\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gaf.kleve.de\\\/hp\\\/#website\"},\"datePublished\":\"2024-09-10T09:02:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gaf.kleve.de\\\/hp\\\/event\\\/klassenfahrt-jahrgang-10-4\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gaf.kleve.de\\\/hp\\\/event\\\/klassenfahrt-jahrgang-10-4\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gaf.kleve.de\\\/hp\\\/event\\\/klassenfahrt-jahrgang-10-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/gaf.kleve.de\\\/hp\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/gaf.kleve.de\\\/hp\\\/event\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Klassenfahrt Jahrgang 10\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gaf.kleve.de\\\/hp\\\/#website\",\"url\":\"https:\\\/\\\/gaf.kleve.de\\\/hp\\\/\",\"name\":\"Gesamtschule am Forstgarten - Voneinander und miteinander lernen in Kleves gr\u00fcner Mitte\",\"description\":\"Gesamtschule am Forstgarten - Voneinander und miteinander lernen in Kleves gr\u00fcner Mitte\",\"publisher\":{\"@id\":\"https:\\\/\\\/gaf.kleve.de\\\/hp\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gaf.kleve.de\\\/hp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gaf.kleve.de\\\/hp\\\/#organization\",\"name\":\"Gesamtschule am Forstgarten Kleve\",\"url\":\"https:\\\/\\\/gaf.kleve.de\\\/hp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/gaf.kleve.de\\\/hp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gaf.kleve.de\\\/hp\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Logo_GaF_RGB.png\",\"contentUrl\":\"https:\\\/\\\/gaf.kleve.de\\\/hp\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Logo_GaF_RGB.png\",\"width\":500,\"height\":286,\"caption\":\"Gesamtschule am Forstgarten Kleve\"},\"image\":{\"@id\":\"https:\\\/\\\/gaf.kleve.de\\\/hp\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/gaf_gesamtschuleamforstgarten\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Klassenfahrt Jahrgang 10 - Gesamtschule am Forstgarten Kleve","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gaf.kleve.de\/hp\/event\/klassenfahrt-jahrgang-10-4\/","og_locale":"de_DE","og_type":"article","og_title":"Klassenfahrt Jahrgang 10 - Gesamtschule am Forstgarten Kleve","og_url":"https:\/\/gaf.kleve.de\/hp\/event\/klassenfahrt-jahrgang-10-4\/","og_site_name":"Gesamtschule am Forstgarten Kleve","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gaf.kleve.de\/hp\/event\/klassenfahrt-jahrgang-10-4\/","url":"https:\/\/gaf.kleve.de\/hp\/event\/klassenfahrt-jahrgang-10-4\/","name":"Klassenfahrt Jahrgang 10 - Gesamtschule am Forstgarten Kleve","isPartOf":{"@id":"https:\/\/gaf.kleve.de\/hp\/#website"},"datePublished":"2024-09-10T09:02:37+00:00","breadcrumb":{"@id":"https:\/\/gaf.kleve.de\/hp\/event\/klassenfahrt-jahrgang-10-4\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gaf.kleve.de\/hp\/event\/klassenfahrt-jahrgang-10-4\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/gaf.kleve.de\/hp\/event\/klassenfahrt-jahrgang-10-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/gaf.kleve.de\/hp\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/gaf.kleve.de\/hp\/event\/"},{"@type":"ListItem","position":3,"name":"Klassenfahrt Jahrgang 10"}]},{"@type":"WebSite","@id":"https:\/\/gaf.kleve.de\/hp\/#website","url":"https:\/\/gaf.kleve.de\/hp\/","name":"Gesamtschule am Forstgarten - Voneinander und miteinander lernen in Kleves gr\u00fcner Mitte","description":"Gesamtschule am Forstgarten - Voneinander und miteinander lernen in Kleves gr\u00fcner Mitte","publisher":{"@id":"https:\/\/gaf.kleve.de\/hp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gaf.kleve.de\/hp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/gaf.kleve.de\/hp\/#organization","name":"Gesamtschule am Forstgarten Kleve","url":"https:\/\/gaf.kleve.de\/hp\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/gaf.kleve.de\/hp\/#\/schema\/logo\/image\/","url":"https:\/\/gaf.kleve.de\/hp\/wp-content\/uploads\/2023\/05\/Logo_GaF_RGB.png","contentUrl":"https:\/\/gaf.kleve.de\/hp\/wp-content\/uploads\/2023\/05\/Logo_GaF_RGB.png","width":500,"height":286,"caption":"Gesamtschule am Forstgarten Kleve"},"image":{"@id":"https:\/\/gaf.kleve.de\/hp\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/gaf_gesamtschuleamforstgarten\/"]}]}},"_links":{"self":[{"href":"https:\/\/gaf.kleve.de\/hp\/wp-json\/wp\/v2\/event\/4656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gaf.kleve.de\/hp\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/gaf.kleve.de\/hp\/wp-json\/wp\/v2\/types\/event"}],"author":[{"embeddable":true,"href":"https:\/\/gaf.kleve.de\/hp\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/gaf.kleve.de\/hp\/wp-json\/wp\/v2\/comments?post=4656"}],"version-history":[{"count":1,"href":"https:\/\/gaf.kleve.de\/hp\/wp-json\/wp\/v2\/event\/4656\/revisions"}],"predecessor-version":[{"id":4657,"href":"https:\/\/gaf.kleve.de\/hp\/wp-json\/wp\/v2\/event\/4656\/revisions\/4657"}],"wp:attachment":[{"href":"https:\/\/gaf.kleve.de\/hp\/wp-json\/wp\/v2\/media?parent=4656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gaf.kleve.de\/hp\/wp-json\/wp\/v2\/categories?post=4656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gaf.kleve.de\/hp\/wp-json\/wp\/v2\/tags?post=4656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}